{"id":74,"date":"2024-10-02T15:15:21","date_gmt":"2024-10-02T13:15:21","guid":{"rendered":"https:\/\/hafo.amore.raidberry.com\/?page_id=74"},"modified":"2026-02-10T13:26:29","modified_gmt":"2026-02-10T12:26:29","slug":"sapi-winde","status":"publish","type":"page","link":"https:\/\/www.hafo.co.at\/it\/sapi-winde\/","title":{"rendered":"Argano SAPI"},"content":{"rendered":"<h1>\n\t\t\tArgano SAPI\t<\/h1>\n\t<p>\u200bKraftvoll ziehen &#8211; ohne gro\u00dfe Investition.<\/p>\n<h2>\n\t\t\tVorteile &#038; Funktionsweise\t<\/h2>\n\t\t<p>Con una forza di trazione da 900 a 1450 kg e una lunghezza del cavo da 35 a 50 metri, l'argano SAPI copre la gamma in cui la trazione manuale \u00e8 troppo faticosa ma non \u00e8 necessario un argano di grandi dimensioni.<\/p>\n<p>Grazie alla staffa a cambio rapido, l'argano SAPI pu\u00f2 essere montato facilmente e senza attrezzi su diverse attrezzature forestali, come gru, pinze da taglio, spaccalegna o bracci di escavatori. La staffa a elica rotante a 360\u00b0 garantisce una guida ottimale del cavo in tutte le direzioni. Con un peso di soli 20-30,5 kg (a seconda del modello), il verricello SAPI \u00e8 facile da trasportare e pu\u00f2 essere utilizzato in modo flessibile.<\/p>\n<p><strong>Con l'argano SAPI \u00e8 possibile utilizzare le macchine forestali esistenti in modo pi\u00f9 efficiente e ridurre lo sforzo fisico.<\/strong><\/p>\n<figure itemscope itemtype=\"https:\/\/schema.org\/ImageObject\">\n\t\t\t\t<a href=\"https:\/\/www.hafo.co.at\/wp-content\/uploads\/2026\/01\/Vorteile-Sapiwinde.png\"  target=\"_self\" itemprop=\"url\">\n\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.hafo.co.at\/wp-content\/uploads\/2026\/01\/Vorteile-Sapiwinde-600x399.png\" alt=\"Vorteile Sapiwinde\" height=\"399\" width=\"600\" title=\"Vorteile Sapiwinde\" onerror=\"this.style.display='none'\" loading=\"lazy\" \/>\n\t\t\t\t<\/a>\n\t<\/figure>\n<h2>\n\t\t\tVantaggi\t<\/h2>\n\t<ul>\n<li>Sistema di argani portatili<\/li>\n<li>Facile installazione grazie alla staffa a cambio rapido<\/li>\n<li>Peso ridotto<\/li>\n<li>Non \u00e8 necessario un cavo aggiuntivo sulla punta della gru<\/li>\n<li>Semplice collegamento all'unit\u00e0 di controllo a doppio effetto<\/li>\n<li>Pu\u00f2 essere combinato con la radio<\/li>\n<li>Dimensioni compatte<\/li>\n<li>Design personalizzato grazie alle diverse console<\/li>\n<li>Ridurre al minimo i danni alla schiena attraverso la movimentazione con la gru<\/li>\n<li>Guida ottimale del cavo grazie alla finestra a rulli o alla puleggia a rulli<\/li>\n<\/ul>\n\t\t<iframe loading=\"lazy\" title=\"Sapiwinde im  Einsatz 1080 x 1350 px\" width=\"500\" height=\"375\" src=\"https:\/\/www.youtube.com\/embed\/2mlOQFt4AYk?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\t\n\t\t<h3><strong>Un verricello, molti usi possibili.<\/strong><\/h3>L'argano a cavo idraulico compatto \u00e8 ideale per molti lavori di silvicoltura, giardinaggio e paesaggistica:\n<ul>\n<li>Tirare su alberi o parti di alberi al di fuori del raggio d'azione della gru.<\/li>\n<li>Rimozione e taglio di arbusti<\/li>\n<li data-start=\"857\" data-end=\"898\">Supporto per il giardinaggio<\/li>\n<li data-start=\"901\" data-end=\"955\">Interventi di manutenzione in aree di difficile accesso<\/li>\n<li data-start=\"958\" data-end=\"1014\">Facile lavoro di inversione senza danneggiare il pavimento<\/li>\n<\/ul>\n<h2>\n\t\t\tAree di applicazione\t<\/h2>\n\t<p>Facile da montare sulle attrezzature forestali esistenti:<\/p>\n\t<h3>Braccio principale della gru<\/h3>\n<figure itemscope itemtype=\"https:\/\/schema.org\/ImageObject\">\n\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.hafo.co.at\/wp-content\/uploads\/2024\/11\/Sapiwinde-auf-Kran-SAPI-winde.webp\" alt=\"Argano Sapi su gru Argano SAPI\" height=\"900\" width=\"1600\" title=\"Argano Sapi su gru Argano SAPI\" onerror=\"this.style.display='none'\" loading=\"lazy\" \/>\n\t<\/figure>\n\t<h3>Punta della gru (Stepa)<\/h3>\n<figure itemscope itemtype=\"https:\/\/schema.org\/ImageObject\">\n\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.hafo.co.at\/wp-content\/uploads\/2024\/11\/SAPI-Kranspitze.webp\" alt=\"Punta della gru SAPI\" height=\"900\" width=\"1600\" title=\"Punta della gru SAPI\" onerror=\"this.style.display='none'\" loading=\"lazy\" \/>\n\t<\/figure>\n\t<h3>Inoltro<\/h3>\n<figure itemscope itemtype=\"https:\/\/schema.org\/ImageObject\">\n\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.hafo.co.at\/wp-content\/uploads\/2024\/11\/SAPI-Winde-am-Rueckewagen-900.jpg\" alt=\"Argano SAPI sul carrello posteriore-900\" height=\"900\" width=\"1600\" title=\"Argano SAPI sul carrello posteriore-900\" onerror=\"this.style.display='none'\" loading=\"lazy\" \/>\n\t<\/figure>\n\t<h3>Braccio principale della gru<\/h3>\n<figure itemscope itemtype=\"https:\/\/schema.org\/ImageObject\">\n\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.hafo.co.at\/wp-content\/uploads\/2024\/11\/SAPI-Winde-am-Baggerarm-900.webp\" alt=\"Argano SAPI su braccio escavatore-900\" height=\"900\" width=\"1600\" title=\"Argano SAPI su braccio escavatore-900\" onerror=\"this.style.display='none'\" loading=\"lazy\" \/>\n\t<\/figure>\n<h2>\n\t\t\tIn pratica\t<\/h2>\n\t\t\t\t<a\n\t\t\thref=\"https:\/\/www.hafo.co.at\/wp-content\/uploads\/2025\/01\/Sapiwinde_holzkran-scaled.jpg\"\n\t\t\t\t\t\tdata-fancybox=\"images\" \n\t\t\ttitle=\"Gru di legno Sapiwinde\" \n\t\t\t\t\t\tdata-description=\"\" \n\t\t\titemprop=\"contentUrl\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.hafo.co.at\/wp-content\/uploads\/2025\/01\/Sapiwinde_holzkran-scaled.jpg\" alt=\"Argano Sapi sulla punta della gru\" data-no-lazy=\"1\" itemprop=\"thumbnail\" width=\"1920\" height=\"2560\" \/>\n\t\t\t<!-- Overlay Wrapper -->\n\t\t\t <!-- Overlay Wrapper Closed -->\n\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<meta itemprop=\"width\" content=\"1920\" \/>\n\t\t\t<meta itemprop=\"height\" content=\"2560\" \/>\n\t\t\t\t<a\n\t\t\thref=\"https:\/\/www.hafo.co.at\/wp-content\/uploads\/2025\/01\/IMG-20230228-WA0007.jpg\"\n\t\t\t\t\t\tdata-fancybox=\"images\" \n\t\t\ttitle=\"Argano Sapi su gru\" \n\t\t\t\t\t\tdata-description=\"\" \n\t\t\titemprop=\"contentUrl\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.hafo.co.at\/wp-content\/uploads\/2025\/01\/IMG-20230228-WA0007.jpg\" alt=\"Argano Sapi montato su gru\" data-no-lazy=\"1\" itemprop=\"thumbnail\" width=\"2048\" height=\"1536\" \/>\n\t\t\t<!-- Overlay Wrapper -->\n\t\t\t <!-- Overlay Wrapper Closed -->\n\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<meta itemprop=\"width\" content=\"2048\" \/>\n\t\t\t<meta itemprop=\"height\" content=\"1536\" \/>\n\t\t\t\t<a\n\t\t\thref=\"https:\/\/www.hafo.co.at\/wp-content\/uploads\/2024\/11\/HAFO-SAPI-Winde-Referenzen-7-1.jpg\"\n\t\t\t\t\t\tdata-fancybox=\"images\" \n\t\t\ttitle=\"HAFO-SAPI-Windlass-Riferimenti-7-1\" \n\t\t\t\t\t\tdata-description=\"\" \n\t\t\titemprop=\"contentUrl\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.hafo.co.at\/wp-content\/uploads\/2024\/11\/HAFO-SAPI-Winde-Referenzen-7-1.jpg\" alt=\"\" data-no-lazy=\"1\" itemprop=\"thumbnail\" width=\"2000\" height=\"1500\" \/>\n\t\t\t<!-- Overlay Wrapper -->\n\t\t\t <!-- Overlay Wrapper Closed -->\n\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<meta itemprop=\"width\" content=\"2000\" \/>\n\t\t\t<meta itemprop=\"height\" content=\"1500\" \/>\n\t\t\t\t<a\n\t\t\thref=\"https:\/\/www.hafo.co.at\/wp-content\/uploads\/2025\/01\/IMG-20181025-WA0022-1.jpg\"\n\t\t\t\t\t\tdata-fancybox=\"images\" \n\t\t\ttitle=\"IMG-20181025-WA0022 1\" \n\t\t\t\t\t\tdata-description=\"\" \n\t\t\titemprop=\"contentUrl\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.hafo.co.at\/wp-content\/uploads\/2025\/01\/IMG-20181025-WA0022-1.jpg\" alt=\"Argano Sapi su gru\" data-no-lazy=\"1\" itemprop=\"thumbnail\" width=\"1098\" height=\"665\" \/>\n\t\t\t<!-- Overlay Wrapper -->\n\t\t\t <!-- Overlay Wrapper Closed -->\n\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<meta itemprop=\"width\" content=\"1098\" \/>\n\t\t\t<meta itemprop=\"height\" content=\"665\" \/>\n\t\t\t\t<a\n\t\t\thref=\"https:\/\/www.hafo.co.at\/wp-content\/uploads\/2024\/11\/WhatsApp-Image-2019-11-06-at-06.58.52-3-1.jpeg\"\n\t\t\t\t\t\tdata-fancybox=\"images\" \n\t\t\ttitle=\"WhatsApp-Image-2019-11-06-at-06.58.52-3\" \n\t\t\t\t\t\tdata-description=\"\" \n\t\t\titemprop=\"contentUrl\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.hafo.co.at\/wp-content\/uploads\/2024\/11\/WhatsApp-Image-2019-11-06-at-06.58.52-3-1.jpeg\" alt=\"\" data-no-lazy=\"1\" itemprop=\"thumbnail\" width=\"1600\" height=\"1200\" \/>\n\t\t\t<!-- Overlay Wrapper -->\n\t\t\t <!-- Overlay Wrapper Closed -->\n\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<meta itemprop=\"width\" content=\"1600\" \/>\n\t\t\t<meta itemprop=\"height\" content=\"1200\" \/>\n\t\t\t\t<a\n\t\t\thref=\"https:\/\/www.hafo.co.at\/wp-content\/uploads\/2024\/11\/HAFO-SAPI-Winde-Referenzen-7.jpg\"\n\t\t\t\t\t\tdata-fancybox=\"images\" \n\t\t\ttitle=\"HAFO-SAPI-Windlass-Riferimenti-7\" \n\t\t\t\t\t\tdata-description=\"\" \n\t\t\titemprop=\"contentUrl\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.hafo.co.at\/wp-content\/uploads\/2024\/11\/HAFO-SAPI-Winde-Referenzen-7.jpg\" alt=\"\" data-no-lazy=\"1\" itemprop=\"thumbnail\" width=\"2000\" height=\"1500\" \/>\n\t\t\t<!-- Overlay Wrapper -->\n\t\t\t <!-- Overlay Wrapper Closed -->\n\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<meta itemprop=\"width\" content=\"2000\" \/>\n\t\t\t<meta itemprop=\"height\" content=\"1500\" \/>\n\t\t\t\t<a\n\t\t\thref=\"https:\/\/www.hafo.co.at\/wp-content\/uploads\/2024\/11\/HAFO-SAPI-Winde-Referenzen-14.jpg\"\n\t\t\t\t\t\tdata-fancybox=\"images\" \n\t\t\ttitle=\"HAFO-SAPI-Windlass-Riferimenti-14\" \n\t\t\t\t\t\tdata-description=\"\" \n\t\t\titemprop=\"contentUrl\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.hafo.co.at\/wp-content\/uploads\/2024\/11\/HAFO-SAPI-Winde-Referenzen-14.jpg\" alt=\"\" data-no-lazy=\"1\" itemprop=\"thumbnail\" width=\"1500\" height=\"844\" \/>\n\t\t\t<!-- Overlay Wrapper -->\n\t\t\t <!-- Overlay Wrapper Closed -->\n\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<meta itemprop=\"width\" content=\"1500\" \/>\n\t\t\t<meta itemprop=\"height\" content=\"844\" \/>\n\t\t\t\t<a\n\t\t\thref=\"https:\/\/www.hafo.co.at\/wp-content\/uploads\/2024\/11\/HAFO-SAPI-Winde-Referenzen-15.jpg\"\n\t\t\t\t\t\tdata-fancybox=\"images\" \n\t\t\ttitle=\"HAFO-SAPI-Windlass-Riferimenti-15\" \n\t\t\t\t\t\tdata-description=\"\" \n\t\t\titemprop=\"contentUrl\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.hafo.co.at\/wp-content\/uploads\/2024\/11\/HAFO-SAPI-Winde-Referenzen-15.jpg\" alt=\"\" data-no-lazy=\"1\" itemprop=\"thumbnail\" width=\"1600\" height=\"1200\" \/>\n\t\t\t<!-- Overlay Wrapper -->\n\t\t\t <!-- Overlay Wrapper Closed -->\n\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<meta itemprop=\"width\" content=\"1600\" \/>\n\t\t\t<meta itemprop=\"height\" content=\"1200\" \/>\n\t\t\t\t<a\n\t\t\thref=\"https:\/\/www.hafo.co.at\/wp-content\/uploads\/2024\/11\/HAFO-SAPI-Winde-Referenzen-24-1.jpg\"\n\t\t\t\t\t\tdata-fancybox=\"images\" \n\t\t\ttitle=\"HAFO-SAPI-Windlass-Riferimenti-24-1\" \n\t\t\t\t\t\tdata-description=\"\" \n\t\t\titemprop=\"contentUrl\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.hafo.co.at\/wp-content\/uploads\/2024\/11\/HAFO-SAPI-Winde-Referenzen-24-1.jpg\" alt=\"\" data-no-lazy=\"1\" itemprop=\"thumbnail\" width=\"1500\" height=\"844\" \/>\n\t\t\t<!-- Overlay Wrapper -->\n\t\t\t <!-- Overlay Wrapper Closed -->\n\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<meta itemprop=\"width\" content=\"1500\" \/>\n\t\t\t<meta itemprop=\"height\" content=\"844\" \/>\n\t\t\t\t<a\n\t\t\thref=\"https:\/\/www.hafo.co.at\/wp-content\/uploads\/2024\/11\/SPAI-Winde-kran-32.jpeg\"\n\t\t\t\t\t\tdata-fancybox=\"images\" \n\t\t\ttitle=\"Gru ad argano SPAI 32\" \n\t\t\t\t\t\tdata-description=\"\" \n\t\t\titemprop=\"contentUrl\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.hafo.co.at\/wp-content\/uploads\/2024\/11\/SPAI-Winde-kran-32.jpeg\" alt=\"\" data-no-lazy=\"1\" itemprop=\"thumbnail\" width=\"1600\" height=\"1200\" \/>\n\t\t\t<!-- Overlay Wrapper -->\n\t\t\t <!-- Overlay Wrapper Closed -->\n\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<meta itemprop=\"width\" content=\"1600\" \/>\n\t\t\t<meta itemprop=\"height\" content=\"1200\" \/>\n\t\t\t\t<a\n\t\t\thref=\"https:\/\/www.hafo.co.at\/wp-content\/uploads\/2024\/11\/SPAI-Winde-kran-33.jpeg\"\n\t\t\t\t\t\tdata-fancybox=\"images\" \n\t\t\ttitle=\"Gru ad argano SPAI 33\" \n\t\t\t\t\t\tdata-description=\"\" \n\t\t\titemprop=\"contentUrl\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.hafo.co.at\/wp-content\/uploads\/2024\/11\/SPAI-Winde-kran-33.jpeg\" alt=\"\" data-no-lazy=\"1\" itemprop=\"thumbnail\" width=\"1600\" height=\"1200\" \/>\n\t\t\t<!-- Overlay Wrapper -->\n\t\t\t <!-- Overlay Wrapper Closed -->\n\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<meta itemprop=\"width\" content=\"1600\" \/>\n\t\t\t<meta itemprop=\"height\" content=\"1200\" \/>\n\t\t\t\t<a\n\t\t\thref=\"https:\/\/www.hafo.co.at\/wp-content\/uploads\/2025\/01\/20240320_101855-scaled.jpg\"\n\t\t\t\t\t\tdata-fancybox=\"images\" \n\t\t\ttitle=\"Argano Sapi su gru Krapn\" \n\t\t\t\t\t\tdata-description=\"\" \n\t\t\titemprop=\"contentUrl\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.hafo.co.at\/wp-content\/uploads\/2025\/01\/20240320_101855-scaled.jpg\" alt=\"Argano Sapi su gru Krapn\" data-no-lazy=\"1\" itemprop=\"thumbnail\" width=\"2560\" height=\"1920\" \/>\n\t\t\t<!-- Overlay Wrapper -->\n\t\t\t <!-- Overlay Wrapper Closed -->\n\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<meta itemprop=\"width\" content=\"2560\" \/>\n\t\t\t<meta itemprop=\"height\" content=\"1920\" \/>\n\t\t\t\t<a\n\t\t\thref=\"https:\/\/www.hafo.co.at\/wp-content\/uploads\/2026\/02\/20250307_105511-scaled.jpg\"\n\t\t\t\t\t\tdata-fancybox=\"images\" \n\t\t\ttitle=\"20250307_105511\" \n\t\t\t\t\t\tdata-description=\"HAFO Sapiwinde auf Kran\" \n\t\t\titemprop=\"contentUrl\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.hafo.co.at\/wp-content\/uploads\/2026\/02\/20250307_105511-scaled.jpg\" alt=\"HAFO Sapiwinde auf Kran\" data-no-lazy=\"1\" itemprop=\"thumbnail\" width=\"1441\" height=\"2560\" \/>\n\t\t\t<!-- Overlay Wrapper -->\n\t\t\t <!-- Overlay Wrapper Closed -->\n\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<meta itemprop=\"width\" content=\"1441\" \/>\n\t\t\t<meta itemprop=\"height\" content=\"2560\" \/>\n\t\t\t\t<a\n\t\t\thref=\"https:\/\/www.hafo.co.at\/wp-content\/uploads\/2026\/02\/20250307_105526-scaled.jpg\"\n\t\t\t\t\t\tdata-fancybox=\"images\" \n\t\t\ttitle=\"20250307_105526\" \n\t\t\t\t\t\tdata-description=\"HAFO Sapiwinde auf Kran\" \n\t\t\titemprop=\"contentUrl\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.hafo.co.at\/wp-content\/uploads\/2026\/02\/20250307_105526-scaled.jpg\" alt=\"HAFO Sapiwinde auf Kran\" data-no-lazy=\"1\" itemprop=\"thumbnail\" width=\"1441\" height=\"2560\" \/>\n\t\t\t<!-- Overlay Wrapper -->\n\t\t\t <!-- Overlay Wrapper Closed -->\n\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<meta itemprop=\"width\" content=\"1441\" \/>\n\t\t\t<meta itemprop=\"height\" content=\"2560\" \/>\n\t\t\t\t<a\n\t\t\thref=\"https:\/\/www.hafo.co.at\/wp-content\/uploads\/2026\/02\/20250307_105615-scaled.jpg\"\n\t\t\t\t\t\tdata-fancybox=\"images\" \n\t\t\ttitle=\"20250307_105615\" \n\t\t\t\t\t\tdata-description=\"HAFO Sapiwinde auf Kran\" \n\t\t\titemprop=\"contentUrl\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.hafo.co.at\/wp-content\/uploads\/2026\/02\/20250307_105615-scaled.jpg\" alt=\"HAFO Sapiwinde auf Kran\" data-no-lazy=\"1\" itemprop=\"thumbnail\" width=\"1441\" height=\"2560\" \/>\n\t\t\t<!-- Overlay Wrapper -->\n\t\t\t <!-- Overlay Wrapper Closed -->\n\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<meta itemprop=\"width\" content=\"1441\" \/>\n\t\t\t<meta itemprop=\"height\" content=\"2560\" \/>\n\t\t\t\t<a\n\t\t\thref=\"https:\/\/www.hafo.co.at\/wp-content\/uploads\/2026\/02\/image1-scaled.jpeg\"\n\t\t\t\t\t\tdata-fancybox=\"images\" \n\t\t\ttitle=\"image1\" \n\t\t\t\t\t\tdata-description=\"Sapiwinde HAFO\" \n\t\t\titemprop=\"contentUrl\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.hafo.co.at\/wp-content\/uploads\/2026\/02\/image1-scaled.jpeg\" alt=\"Sapiwinde HAFO\" data-no-lazy=\"1\" itemprop=\"thumbnail\" width=\"1920\" height=\"2560\" \/>\n\t\t\t<!-- Overlay Wrapper -->\n\t\t\t <!-- Overlay Wrapper Closed -->\n\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<meta itemprop=\"width\" content=\"1920\" \/>\n\t\t\t<meta itemprop=\"height\" content=\"2560\" \/>\n\t<p>Il nostro video di prodotto per il verricello SAPI<\/p>\n\t\t<iframe loading=\"lazy\" width=\"624\" height=\"351\" src=\"https:\/\/www.youtube.com\/embed\/AsVj1lWMAbo\" title=\"HAFO GmbH Haselsteiner Forsttechnik Argano portatile Sapi www.hafo.co.at\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\t\n\t\t\t<a href=\"https:\/\/www.hafo.co.at\/it\/negozio\/\"  target=\"_self\">\n\t\t\t\t\t\t\tacquista ora\n\t\t\t\t\t<\/a>\n<h2>\n\t\t\tDati tecnici\t<\/h2>\n\t<p>Tutti i dettagli<\/p>\n<table  data-tablesaw-minimap>\n\t\t\t<thead>\n\t\t<tr>\n\t\t\t<th id=\"pp-table-col-1\" scope=\"col\" data-tablesaw-sortable-col>\t\t\t\t\t\n\t\t\t\t\t<\/th><th id=\"pp-table-col-2\" scope=\"col\" data-tablesaw-sortable-col>\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\tFacile\t\t\t\t\t\n\t\t\t\t\t<\/th><th id=\"pp-table-col-3\" scope=\"col\" data-tablesaw-sortable-col>\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\tFacile+\t\t\t\t\t\n\t\t\t\t\t<\/th><th id=\"pp-table-col-4\" scope=\"col\" data-tablesaw-sortable-col>\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\tPro\t\t\t\t\t\n\t\t\t\t\t<\/th>\t\t<\/tr>\n\t<\/thead>\n\t\t<tbody>\n\t\t<tr data-row-index=\"1\"><td>Pressione di esercizio continua:<\/td><td>180 bar<\/td><td>210 bar<\/td><td>210 bar<\/td><\/tr><tr data-row-index=\"2\"><td>pressione massima di esercizio:<\/td><td>200 bar<\/td><td>200 bar<\/td><td>250 bar<\/td><\/tr><tr data-row-index=\"3\"><td>quantit\u00e0 di olio richiesta:<\/td><td>min. 20l &#8211; max. 60l \/ min<\/td><td>min. 20l &#8211; max. 60l \/ min<\/td><td>min. 20l &#8211; max. 60l \/ min<\/td><\/tr><tr data-row-index=\"4\"><td>forza di trazione massima:<\/td><td>850 kg<\/td><td>1000 kg<\/td><td>1450 kg<\/td><\/tr><tr data-row-index=\"5\"><td>velocit\u00e0 media della fune:<\/td><td>fino a 3 m\/s a 60 l \/ min<\/td><td>fino a 3 m\/s a 60 l \/ min<\/td><td>fino a 2 m\/s a 60 l \/ min.<\/td><\/tr><tr data-row-index=\"6\"><td>Peso senza corda:<\/td><td>20 kg<\/td><td>22 kg<\/td><td>30,5 kg<\/td><\/tr><tr data-row-index=\"7\"><td>Presa di corda massima:<\/td><td>50 m \/ 5 mm<\/td><td>50 m \/ 5 mm<\/td><td>50 m \/ 5 mm<\/td><\/tr>\t<\/tbody>\n<\/table>\n<figure itemscope itemtype=\"https:\/\/schema.org\/ImageObject\">\n\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.hafo.co.at\/wp-content\/uploads\/2026\/01\/Zeichnung-scaled.jpg\" alt=\"Sapiwinde Zeichnung\" height=\"2551\" width=\"2560\" title=\"Zeichnung\" onerror=\"this.style.display='none'\" loading=\"lazy\" \/>\n\t<\/figure>\n<figure itemscope itemtype=\"https:\/\/schema.org\/ImageObject\">\n\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.hafo.co.at\/wp-content\/uploads\/2024\/12\/Sapiwinde_set-scaled.jpg\" alt=\"Sapiwinde_set\" height=\"2558\" width=\"2560\" title=\"Sapiwinde_set\" onerror=\"this.style.display='none'\" loading=\"lazy\" \/>\n\t<\/figure>\n\t\t\t<a href=\"https:\/\/www.hafo.co.at\/it\/negozio\/\"  target=\"_self\">\n\t\t\t\t\t\t\tAcquista direttamente ora\n\t\t\t\t\t<\/a>\n\t\t\t<a href=\"https:\/\/www.hafo.co.at\/it\/categoria-di-prodotto\/sapi-winde\/zubehor-sw\/\"  target=\"_self\">\n\t\t\t\t\t\t\tAccessori\n\t\t\t<\/a>\n\t<p>Per il perfetto funzionamento del verricello ausiliario sono necessari, oltre al verricello, una staffa, un cavo di plastica, un blocco idraulico e tubi idraulici, una puleggia e (opzionalmente) una scatola di interruttori.<\/p>\n\t\t\t<a href=\"https:\/\/www.hafo.co.at\/it\/sapi-winde\/faq-sapi-winde\/\"  target=\"_self\">\n\t\t\t\t\t\t\tDomande frequenti\n\t\t\t<\/a>\n\t<p>Il verricello pu\u00f2 essere montato su qualsiasi verricello a cavo? Ho bisogno di una radio personale? Abbiamo risposto a queste e ad altre domande frequenti nelle nostre FAQ.<\/p>\n\t\t\t<a href=\"https:\/\/www.hafo.co.at\/it\/sapi-winde\/videos-sapi-winde\/\"  target=\"_self\">\n\t\t\t\t\t\t\tVideo\n\t\t\t<\/a>\n\t<p>Volete vedere il verricello ausiliario in azione? Nessun problema, abbiamo filmato diverse applicazioni per voi. Provate i nostri prodotti in azione.<\/p>","protected":false},"excerpt":{"rendered":"<p>SAPI Winde \u200bKraftvoll ziehen &#8211; ohne gro\u00dfe Investition. Vorteile &#038; Funktionsweise Mit einer Zugkraft von 900 bis 1450 kg und einer Seilfassung von 35 bis 50 Metern deckt die SAPI Winde den Bereich ab, in dem manuelles Ziehen zu anstrengend ist, aber eine gro\u00dfe Winde nicht erforderlich ist.\u200b Dank der Schnellwechselkonsole l\u00e4sst sich die SAPI&hellip;<\/p>","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-74","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>SAPI Winde - HAFO Forsttechnik<\/title>\n<meta name=\"description\" content=\"SAPI Winde von HAFO - hydraulische Winde als Erg\u00e4nzung f\u00fcr Ihre Forstmaschinen\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.hafo.co.at\/it\/sapi-winde\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SAPI Winde - HAFO Forsttechnik\" \/>\n<meta property=\"og:description\" content=\"SAPI Winde von HAFO - hydraulische Winde als Erg\u00e4nzung f\u00fcr Ihre Forstmaschinen\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.hafo.co.at\/it\/sapi-winde\/\" \/>\n<meta property=\"og:site_name\" content=\"HAFO Forsttechnik\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/p\/HAFO-100064275891778\/?locale=de_DE\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-10T12:26:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.hafo.co.at\/wp-content\/uploads\/2026\/01\/Vorteile-Sapiwinde-600x399.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.hafo.co.at\/sapi-winde\/\",\"url\":\"https:\/\/www.hafo.co.at\/sapi-winde\/\",\"name\":\"SAPI Winde - HAFO Forsttechnik\",\"isPartOf\":{\"@id\":\"https:\/\/www.hafo.co.at\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.hafo.co.at\/sapi-winde\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.hafo.co.at\/sapi-winde\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.hafo.co.at\/wp-content\/uploads\/2026\/01\/Vorteile-Sapiwinde-600x399.png\",\"datePublished\":\"2024-10-02T13:15:21+00:00\",\"dateModified\":\"2026-02-10T12:26:29+00:00\",\"description\":\"SAPI Winde von HAFO - hydraulische Winde als Erg\u00e4nzung f\u00fcr Ihre Forstmaschinen\",\"breadcrumb\":{\"@id\":\"https:\/\/www.hafo.co.at\/sapi-winde\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.hafo.co.at\/sapi-winde\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.hafo.co.at\/sapi-winde\/#primaryimage\",\"url\":\"https:\/\/www.hafo.co.at\/wp-content\/uploads\/2026\/01\/Vorteile-Sapiwinde-600x399.png\",\"contentUrl\":\"https:\/\/www.hafo.co.at\/wp-content\/uploads\/2026\/01\/Vorteile-Sapiwinde-600x399.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.hafo.co.at\/sapi-winde\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/www.hafo.co.at\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"SAPI Winde\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.hafo.co.at\/#website\",\"url\":\"https:\/\/www.hafo.co.at\/\",\"name\":\"HAFO Forsttechnik\",\"description\":\"HAFO Hilfswinden HAFO Sapiwinden, aus Tradition in die Zukunft\",\"publisher\":{\"@id\":\"https:\/\/www.hafo.co.at\/#organization\"},\"alternateName\":\"Haselsteiner Forsttechnik\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.hafo.co.at\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.hafo.co.at\/#organization\",\"name\":\"HAFO Forsttechnik\",\"url\":\"https:\/\/www.hafo.co.at\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.hafo.co.at\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.hafo.co.at\/wp-content\/uploads\/2025\/01\/Icon.png\",\"contentUrl\":\"https:\/\/www.hafo.co.at\/wp-content\/uploads\/2025\/01\/Icon.png\",\"width\":1080,\"height\":1080,\"caption\":\"HAFO Forsttechnik\"},\"image\":{\"@id\":\"https:\/\/www.hafo.co.at\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/p\/HAFO-100064275891778\/?locale=de_DE\",\"https:\/\/www.instagram.com\/hafo.haselsteiner\/\",\"https:\/\/www.youtube.com\/channel\/UCOJhfhsB-vUuG8v6kAf_HEQ\/videos\",\"https:\/\/www.tiktok.com\/@haselsteiner\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Argano SAPI - HAFO Forsttechnik","description":"SAPI Winde von HAFO - hydraulische Winde als Erg\u00e4nzung f\u00fcr Ihre Forstmaschinen","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.hafo.co.at\/it\/sapi-winde\/","og_locale":"it_IT","og_type":"article","og_title":"SAPI Winde - HAFO Forsttechnik","og_description":"SAPI Winde von HAFO - hydraulische Winde als Erg\u00e4nzung f\u00fcr Ihre Forstmaschinen","og_url":"https:\/\/www.hafo.co.at\/it\/sapi-winde\/","og_site_name":"HAFO Forsttechnik","article_publisher":"https:\/\/www.facebook.com\/p\/HAFO-100064275891778\/?locale=de_DE","article_modified_time":"2026-02-10T12:26:29+00:00","og_image":[{"url":"https:\/\/www.hafo.co.at\/wp-content\/uploads\/2026\/01\/Vorteile-Sapiwinde-600x399.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.hafo.co.at\/sapi-winde\/","url":"https:\/\/www.hafo.co.at\/sapi-winde\/","name":"Argano SAPI - HAFO Forsttechnik","isPartOf":{"@id":"https:\/\/www.hafo.co.at\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.hafo.co.at\/sapi-winde\/#primaryimage"},"image":{"@id":"https:\/\/www.hafo.co.at\/sapi-winde\/#primaryimage"},"thumbnailUrl":"https:\/\/www.hafo.co.at\/wp-content\/uploads\/2026\/01\/Vorteile-Sapiwinde-600x399.png","datePublished":"2024-10-02T13:15:21+00:00","dateModified":"2026-02-10T12:26:29+00:00","description":"SAPI Winde von HAFO - hydraulische Winde als Erg\u00e4nzung f\u00fcr Ihre Forstmaschinen","breadcrumb":{"@id":"https:\/\/www.hafo.co.at\/sapi-winde\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.hafo.co.at\/sapi-winde\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.hafo.co.at\/sapi-winde\/#primaryimage","url":"https:\/\/www.hafo.co.at\/wp-content\/uploads\/2026\/01\/Vorteile-Sapiwinde-600x399.png","contentUrl":"https:\/\/www.hafo.co.at\/wp-content\/uploads\/2026\/01\/Vorteile-Sapiwinde-600x399.png"},{"@type":"BreadcrumbList","@id":"https:\/\/www.hafo.co.at\/sapi-winde\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.hafo.co.at\/"},{"@type":"ListItem","position":2,"name":"SAPI Winde"}]},{"@type":"WebSite","@id":"https:\/\/www.hafo.co.at\/#website","url":"https:\/\/www.hafo.co.at\/","name":"Tecnologia forestale HAFO","description":"HAFO Hilfswinden HAFO Sapiwinden, aus Tradition in die Zukunft","publisher":{"@id":"https:\/\/www.hafo.co.at\/#organization"},"alternateName":"Haselsteiner Forsttechnik","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.hafo.co.at\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.hafo.co.at\/#organization","name":"Tecnologia forestale HAFO","url":"https:\/\/www.hafo.co.at\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.hafo.co.at\/#\/schema\/logo\/image\/","url":"https:\/\/www.hafo.co.at\/wp-content\/uploads\/2025\/01\/Icon.png","contentUrl":"https:\/\/www.hafo.co.at\/wp-content\/uploads\/2025\/01\/Icon.png","width":1080,"height":1080,"caption":"HAFO Forsttechnik"},"image":{"@id":"https:\/\/www.hafo.co.at\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/p\/HAFO-100064275891778\/?locale=de_DE","https:\/\/www.instagram.com\/hafo.haselsteiner\/","https:\/\/www.youtube.com\/channel\/UCOJhfhsB-vUuG8v6kAf_HEQ\/videos","https:\/\/www.tiktok.com\/@haselsteiner"]}]}},"_links":{"self":[{"href":"https:\/\/www.hafo.co.at\/it\/wp-json\/wp\/v2\/pages\/74","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hafo.co.at\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.hafo.co.at\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.hafo.co.at\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hafo.co.at\/it\/wp-json\/wp\/v2\/comments?post=74"}],"version-history":[{"count":10,"href":"https:\/\/www.hafo.co.at\/it\/wp-json\/wp\/v2\/pages\/74\/revisions"}],"predecessor-version":[{"id":4981,"href":"https:\/\/www.hafo.co.at\/it\/wp-json\/wp\/v2\/pages\/74\/revisions\/4981"}],"wp:attachment":[{"href":"https:\/\/www.hafo.co.at\/it\/wp-json\/wp\/v2\/media?parent=74"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}